{"id":3621,"date":"2018-05-10T10:26:18","date_gmt":"2018-05-10T08:26:18","guid":{"rendered":"http:\/\/www.nanosilicaldevices.com\/nanosilical-devices-s-r-l-finalist-to-imsa2018\/"},"modified":"2019-07-07T22:05:41","modified_gmt":"2019-07-07T20:05:41","slug":"nanosilical-devices-s-r-l-finalist-to-imsa2018","status":"publish","type":"post","link":"https:\/\/www.nanosilicaldevices.com\/it\/nanosilical-devices-s-r-l-finalist-to-imsa2018\/","title":{"rendered":"NanoSiliCal Devices S.r.l. finalista a IMSA2018"},"content":{"rendered":"<p>La NanoSiliCal Devices S.r.l. \u00e8 tra le finaliste <strong>dell\u2019Italian Master Start-up Award &#8211; Edizione 2018<\/strong> (<strong>IMSA2018<\/strong>). Il premio, che ha sostituito quello denominato \u201cStart up dell\u2019anno\u201d, \u00e8 nato nel 2007 ed \u00e8 a tutt\u2019oggi l\u2019unico su base nazionale che valorizzi i risultati ottenuti sul mercato delle aziende Hi-Tech di recente costituzione. Organizzatore del premio \u00e8 l\u2019associazione PNICube, che si avvale di volta in volta della collaborazione di una delle Istituzioni associate che ospita la cerimonia di premiazione. L\u2019IMSA2018 ha il primario obiettivo di dare visibilit\u00e0 alle aziende innovative giovani che hanno ottenuto importanti risultati sia dal punto di vista economico che sul piano della qualit\u00e0. Con questo premio la PNICube si propone, inoltre, di monitorare i risultati conseguiti con le business plan competition e con le attivit\u00e0 di incubazione svolte dalle Istituzioni associate e dai partners di queste.<!--more--><\/p>\n<p><strong>L\u2019Associazione PNICube<\/strong> nasce nel 2004 per occuparsi di trasferimento tecnologico dalle Universit\u00e0 o Istituti di Ricerca alle imprese innovative e sfrutta l\u2019esperienza maturata nel progetto\u00a0 IUNET e nel Premio Nazionale per l\u2019Innovazione (PNI). L\u2019IUNET era un progetto finanziato nel 2003 dal Ministero delle Attivit\u00e0 Produttive e gestito dall\u2019Associazione Incubatori Universitari, mentre il PNI \u00e8 stato attivato lo stesso anno e prendeva in esame i migliori progetti di impresa basati su idee provenienti dal settore universitario e vincitori di cinque diverse start cup. L\u2019Associazione PNICube ha un consiglio direttivo composto dai rappresentanti dei 15 atenei italiani asssociati. Tra i soci troviamo l\u2019Universit\u00e0 di Pisa, il Politecnico di Milano l\u2019Universit\u00e0 Federico II di Napoli, l\u2019Universit\u00e0 degli Studi di Torino, di Roma \u201cTor Vergata&#8221; e l\u2019Universit\u00e0 della Calabria, Istituto organizzatore della cerimonia di premiazione IMSA2018.<\/p>\n<p>I finalisti di quest\u2019anno sono nove, tra le start-up pi\u00f9 interessanti del panorama imprenditoriale. Tra queste si \u00e8 qualificata per la finale anche la <strong>NanoSiliCal Devices<\/strong>, che sta occupando un importante posto tra le imprese innovative in campo medico. Grazie agli sforzi dei suoi fondatori e del suo team di lavoro, la NanoSiliCal ha saputo tradurre i risultati della ricerca pura in una concreta idea imprenditoriale, capace di attirare l\u2019interesse di finanziatori esteri e di avere un posto in prima fila tra le aziende proponenti progetti di ricerca innovativi in ambito europeo, come confermato dal recente attestato di eccellenza rilasciato dalla Commissione Europea (Seal of excellence).<\/p>\n<p>La cerimonia di premiazione della Start up per l\u2019edizione 2018 dell\u2019IMSA si terr\u00e0 presso l\u2019<strong>Universit\u00e0 della Calabria<\/strong> il 14 Maggio. Sar\u00e0 una giornata completamente dedicata alla valorizzazione delle idee imprenditoriali finaliste, che avranno a disposizione degli stand per la valorizzazione dei loro prodotti ed uno spazio temporale di 5 minuti a testa per presentare la mission aziendale, il team di lavoro e la business idea su cui si basa il piano di sviluppo di ognuna di esse. La NanoSiliCal Devices avr\u00e0 la possibilit\u00e0 di cimentarsi in questa competizione con la solita abnegazione che contraddistingue il team di lavoro, anche contro una agguerrita concorrenza da parte delle altre start up. La giuria giudicante sar\u00e0 composta da sei elementi rappresentanti l\u2019intera filiera del trasferimento tecnologico dalla ricerca alle aziende. Ne fanno parte, infatti, la Dott.ssa Di Somma di \u201cGrow it up\u201d, il Dott. Anselmo della IBAN, il Dott. Mazzei di FinCalabra e la Dott.ssa Staziola di Unicredit, oltre al Dott. Vincent dell\u2019Ambasciata Francese e la Dott.ssa Aliberti del Dept. of International Trade (UK). Oltre al premio IMSA, inoltre, saranno assegnati ben due premi speciali indetti dalle Ambasciate francesi ed Inglesi. Questi ultimi fungeranno da trampolino di lancio per le aziende innovative vincitrici di questi premi speciali e per i loro prodotti, occasione pi\u00f9 che concreta per la NanoSiliCal di farsi conoscere anche oltre frontiera e trovare utili ed importanti collaborazioni con altre aziende francesi ed inglesi interessate alla sua idea di business.<\/p>\n<p>http:\/\/www.pnicube.it\/premio-italian-master-startup-award\/<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3377 aligncenter\" src=\"\/wp-content\/uploads\/2018\/05\/Immagine-prodotto-NanoSilical-Devices-Srl-ultima-versione-300x231.jpg\" alt=\"\" width=\"300\" height=\"231\" srcset=\"https:\/\/www.nanosilicaldevices.com\/wp-content\/uploads\/2018\/05\/Immagine-prodotto-NanoSilical-Devices-Srl-ultima-versione-300x231.jpg 300w, https:\/\/www.nanosilicaldevices.com\/wp-content\/uploads\/2018\/05\/Immagine-prodotto-NanoSilical-Devices-Srl-ultima-versione-768x592.jpg 768w, https:\/\/www.nanosilicaldevices.com\/wp-content\/uploads\/2018\/05\/Immagine-prodotto-NanoSilical-Devices-Srl-ultima-versione-1024x789.jpg 1024w, https:\/\/www.nanosilicaldevices.com\/wp-content\/uploads\/2018\/05\/Immagine-prodotto-NanoSilical-Devices-Srl-ultima-versione.jpg 1396w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\"><strong>La Tecnologia di NanoSiliCal Devices.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La NanoSiliCal Devices S.r.l. \u00e8 tra le finaliste dell\u2019Italian Master Start-up Award &#8211; Edizione 2018 (IMSA2018). Il premio, che ha sostituito quello denominato \u201cStart up dell\u2019anno\u201d, \u00e8 nato nel 2007 ed \u00e8 a tutt\u2019oggi l\u2019unico su base nazionale che valorizzi i risultati ottenuti sul mercato delle aziende Hi-Tech di recente costituzione. Organizzatore del premio \u00e8 &#8230; <a class=\"more-link\" href=\"https:\/\/www.nanosilicaldevices.com\/it\/nanosilical-devices-s-r-l-finalist-to-imsa2018\/\">Continue reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":3622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-3621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"_links":{"self":[{"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/posts\/3621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/comments?post=3621"}],"version-history":[{"count":3,"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/posts\/3621\/revisions"}],"predecessor-version":[{"id":3625,"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/posts\/3621\/revisions\/3625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/media\/3622"}],"wp:attachment":[{"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/media?parent=3621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/categories?post=3621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nanosilicaldevices.com\/it\/wp-json\/wp\/v2\/tags?post=3621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}